{"id":359,"count":5,"description":"","link":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/","name":"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441","slug":"small-business-ru","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441 - ESET Eesti Blogi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441 Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/\" \/>\n<meta property=\"og:site_name\" content=\"ESET Eesti Blogi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/category\\\/small-business-ru\\\/\",\"url\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/category\\\/small-business-ru\\\/\",\"name\":\"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441 - ESET Eesti Blogi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/category\\\/small-business-ru\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/category\\\/small-business-ru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/\",\"name\":\"ESET Eesti Blogi\",\"description\":\"Uudised IT maailmast\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/blog.eset.ee\\\/et\\\/ru\\\/category\\\/small-business-ru\\\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ESET EESTI\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441 - ESET Eesti Blogi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/","og_locale":"ru_RU","og_type":"article","og_title":"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441 Archives","og_url":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/","og_site_name":"ESET Eesti Blogi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/","url":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/","name":"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441 - ESET Eesti Blogi","isPartOf":{"@id":"https:\/\/blog.eset.ee\/et\/ru\/#website"},"breadcrumb":{"@id":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/#breadcrumb"},"inLanguage":"ru-RU"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.eset.ee\/et\/ru\/"},{"@type":"ListItem","position":2,"name":"\u043c\u0430\u043b\u044b\u0439 \u0431\u0438\u0437\u043d\u0435\u0441"}]},{"@type":"WebSite","@id":"https:\/\/blog.eset.ee\/et\/ru\/#website","url":"https:\/\/blog.eset.ee\/et\/ru\/","name":"ESET Eesti Blogi","description":"Uudised IT maailmast","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.eset.ee\/et\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/blog.eset.ee\/et\/ru\/category\/small-business-ru\/#local-main-organization-logo","url":"","contentUrl":"","caption":"ESET EESTI"}]}},"_links":{"self":[{"href":"https:\/\/blog.eset.ee\/et\/ru\/wp-json\/wp\/v2\/categories\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.eset.ee\/et\/ru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.eset.ee\/et\/ru\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.eset.ee\/et\/ru\/wp-json\/wp\/v2\/posts?categories=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}